{"id":1557,"date":"2024-04-22T09:29:34","date_gmt":"2024-04-22T07:29:34","guid":{"rendered":"https:\/\/www.bamstrategieculturali.com\/wikimuseums\/?page_id=1557"},"modified":"2024-06-03T12:50:05","modified_gmt":"2024-06-03T10:50:05","slug":"ospita-wikimuseums","status":"publish","type":"page","link":"https:\/\/www.bamstrategieculturali.com\/wikimuseums\/ospita-wikimuseums\/","title":{"rendered":"Ospita Wikimuseums"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><h4><strong><span style=\"color: #ff6600;\">Hai visto le edizioni passate di Wikimuseums <a href=\"https:\/\/www.bamstrategieculturali.com\/wikimuseums\/programma\/\">Napoli<\/a> e <a href=\"https:\/\/www.bamstrategieculturali.com\/wikimuseums\/cesena\/\">Cesena<\/a> e vorresti portarlo nel tuo museo, archivio o biblioteca? Questa \u00e8 la pagina in cui vediamo come farlo accadere insieme!<\/span><\/strong><\/h4>\n<p>[vc_column][vc_column_text css=&#8221;&#8221;]<span style=\"font-weight: 400;\">Wikimuseums \u00e8 un format pensato per rendere i beni culturali pi\u00f9 accessibili, attraverso il coinvolgimento diretto dei pubblici e delle community nella creazione di contenuti culturali sul patrimonio e la storia del luogo, delle collezioni e dell\u2019istituzione stessa. Il tutto con un <strong>approccio open<\/strong>, <strong>collaborativo<\/strong> <strong>e<\/strong> <strong>attivo<\/strong> sui progetti Wiki, tra cui Wikipedia, OpenStreetMap e Wikidata.<\/span>[\/vc_column] [vc_section][vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<\/p>\n<p>&nbsp;<\/p>\n<h4><span style=\"color: #ff6600;\"><strong><i>Come si fa?<\/i><\/strong><\/span><\/h4>\n<p>[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<span style=\"font-weight: 400;\">Organizzando una maratona di due giorni di formazione, lavoro sulle fonti, creazione o arricchimento di voci online e georeferenziazione dei beni culturali. Un\u2019attivit\u00e0 che permette ai visitatori di diventare co-creatori di conoscenza, mentre si promuove l&#8217;innovazione digitale e si rafforza il legame con la comunit\u00e0.<\/span>[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<span style=\"font-weight: 400;\">Fare Wikimuseums \u00e8 un <strong>lavoro di squadra<\/strong>! Il team di Wikimuseums, formato da persone esperte di comunicazione e dei progetti Wiki, supporteranno il team del tuo museo, archivio o biblioteca nell\u2019organizzazione e nella promozione dell\u2019evento.<\/span>[\/vc_column_text][vc_separator][\/vc_column][\/vc_row][\/vc_section][vc_row][vc_column][vc_column_text css=&#8221;&#8221;]<\/p>\n<h4><span style=\"color: #ff6600;\"><strong>Chi ospiter\u00e0 la prossima tappa di Wikimuseums? Scrivici a info@wikimuseums.com o compila il form qui sotto e iniziamo a organizzarlo insieme!<\/strong><\/span><\/h4>\n<p>[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<script type=\"text\/javascript\">var gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,initializeOnLoaded:function(o){gform.domLoaded&&gform.scriptsLoaded?o():!gform.domLoaded&&gform.scriptsLoaded?window.addEventListener(\"DOMContentLoaded\",o):document.addEventListener(\"gform_main_scripts_loaded\",o)},hooks:{action:{},filter:{}},addAction:function(o,n,r,t){gform.addHook(\"action\",o,n,r,t)},addFilter:function(o,n,r,t){gform.addHook(\"filter\",o,n,r,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,n){gform.removeHook(\"action\",o,n)},removeFilter:function(o,n,r){gform.removeHook(\"filter\",o,n,r)},addHook:function(o,n,r,t,i){null==gform.hooks[o][n]&&(gform.hooks[o][n]=[]);var e=gform.hooks[o][n];null==i&&(i=n+\"_\"+e.length),gform.hooks[o][n].push({tag:i,callable:r,priority:t=null==t?10:t})},doHook:function(n,o,r){var t;if(r=Array.prototype.slice.call(r,1),null!=gform.hooks[n][o]&&((o=gform.hooks[n][o]).sort(function(o,n){return o.priority-n.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==n?t.apply(null,r):r[0]=t.apply(null,r)})),\"filter\"==n)return r[0]},removeHook:function(o,n,t,i){var r;null!=gform.hooks[o][n]&&(r=(r=gform.hooks[o][n]).filter(function(o,n,r){return!!(null!=i&&i!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][n]=r)}});<\/script>\n                <div class='gf_browser_gecko gform_wrapper gform-theme gform-theme--foundation gform-theme--framework gform-theme--orbital' data-form-theme='orbital' data-form-index='0' id='gform_wrapper_1' ><style>#gform_wrapper_1[data-form-index=\"0\"].gform-theme,[data-parent-form=\"1_0\"]{--gf-color-primary: #204ce5;--gf-color-primary-rgb: 32, 76, 229;--gf-color-primary-contrast: #fff;--gf-color-primary-contrast-rgb: 255, 255, 255;--gf-color-primary-darker: #001AB3;--gf-color-primary-lighter: #527EFF;--gf-color-secondary: #fff;--gf-color-secondary-rgb: 255, 255, 255;--gf-color-secondary-contrast: #112337;--gf-color-secondary-contrast-rgb: 17, 35, 55;--gf-color-secondary-darker: #F5F5F5;--gf-color-secondary-lighter: #FFFFFF;--gf-color-out-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-out-ctrl-light-rgb: 17, 35, 55;--gf-color-out-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-out-ctrl-light-lighter: #F5F5F5;--gf-color-out-ctrl-dark: #585e6a;--gf-color-out-ctrl-dark-rgb: 88, 94, 106;--gf-color-out-ctrl-dark-darker: #112337;--gf-color-out-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-color-in-ctrl: #fff;--gf-color-in-ctrl-rgb: 255, 255, 255;--gf-color-in-ctrl-contrast: #112337;--gf-color-in-ctrl-contrast-rgb: 17, 35, 55;--gf-color-in-ctrl-darker: #F5F5F5;--gf-color-in-ctrl-lighter: #FFFFFF;--gf-color-in-ctrl-primary: #204ce5;--gf-color-in-ctrl-primary-rgb: 32, 76, 229;--gf-color-in-ctrl-primary-contrast: #fff;--gf-color-in-ctrl-primary-contrast-rgb: 255, 255, 255;--gf-color-in-ctrl-primary-darker: #001AB3;--gf-color-in-ctrl-primary-lighter: #527EFF;--gf-color-in-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-in-ctrl-light-rgb: 17, 35, 55;--gf-color-in-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-in-ctrl-light-lighter: #F5F5F5;--gf-color-in-ctrl-dark: #585e6a;--gf-color-in-ctrl-dark-rgb: 88, 94, 106;--gf-color-in-ctrl-dark-darker: #112337;--gf-color-in-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-radius: 3px;--gf-font-size-secondary: 14px;--gf-font-size-tertiary: 13px;--gf-icon-ctrl-number: url(\"data:image\/svg+xml,%3Csvg width='8' height='14' viewBox='0 0 8 14' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M4 0C4.26522 5.96046e-08 4.51957 0.105357 4.70711 0.292893L7.70711 3.29289C8.09763 3.68342 8.09763 4.31658 7.70711 4.70711C7.31658 5.09763 6.68342 5.09763 6.29289 4.70711L4 2.41421L1.70711 4.70711C1.31658 5.09763 0.683417 5.09763 0.292893 4.70711C-0.0976311 4.31658 -0.097631 3.68342 0.292893 3.29289L3.29289 0.292893C3.48043 0.105357 3.73478 0 4 0ZM0.292893 9.29289C0.683417 8.90237 1.31658 8.90237 1.70711 9.29289L4 11.5858L6.29289 9.29289C6.68342 8.90237 7.31658 8.90237 7.70711 9.29289C8.09763 9.68342 8.09763 10.3166 7.70711 10.7071L4.70711 13.7071C4.31658 14.0976 3.68342 14.0976 3.29289 13.7071L0.292893 10.7071C-0.0976311 10.3166 -0.0976311 9.68342 0.292893 9.29289Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-select: url(\"data:image\/svg+xml,%3Csvg width='10' height='6' viewBox='0 0 10 6' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M0.292893 0.292893C0.683417 -0.097631 1.31658 -0.097631 1.70711 0.292893L5 3.58579L8.29289 0.292893C8.68342 -0.0976311 9.31658 -0.0976311 9.70711 0.292893C10.0976 0.683417 10.0976 1.31658 9.70711 1.70711L5.70711 5.70711C5.31658 6.09763 4.68342 6.09763 4.29289 5.70711L0.292893 1.70711C-0.0976311 1.31658 -0.0976311 0.683418 0.292893 0.292893Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-search: url(\"data:image\/svg+xml,%3Csvg version='1.1' xmlns='http:\/\/www.w3.org\/2000\/svg' width='640' height='640'%3E%3Cpath d='M256 128c-70.692 0-128 57.308-128 128 0 70.691 57.308 128 128 128 70.691 0 128-57.309 128-128 0-70.692-57.309-128-128-128zM64 256c0-106.039 85.961-192 192-192s192 85.961 192 192c0 41.466-13.146 79.863-35.498 111.248l154.125 154.125c12.496 12.496 12.496 32.758 0 45.254s-32.758 12.496-45.254 0L367.248 412.502C335.862 434.854 297.467 448 256 448c-106.039 0-192-85.962-192-192z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-label-space-y-secondary: var(--gf-label-space-y-md-secondary);--gf-ctrl-border-color: #686e77;--gf-ctrl-size: var(--gf-ctrl-size-md);--gf-ctrl-label-color-primary: #112337;--gf-ctrl-label-color-secondary: #112337;--gf-ctrl-choice-size: var(--gf-ctrl-choice-size-md);--gf-ctrl-checkbox-check-size: var(--gf-ctrl-checkbox-check-size-md);--gf-ctrl-radio-check-size: var(--gf-ctrl-radio-check-size-md);--gf-ctrl-btn-font-size: var(--gf-ctrl-btn-font-size-md);--gf-ctrl-btn-padding-x: var(--gf-ctrl-btn-padding-x-md);--gf-ctrl-btn-size: var(--gf-ctrl-btn-size-md);--gf-ctrl-btn-border-color-secondary: #686e77;--gf-ctrl-file-btn-bg-color-hover: #EBEBEB;--gf-field-pg-steps-number-color: rgba(17, 35, 55, 0.8);}<\/style>\n                        <div class='gform_heading'>\n                            <p class='gform_description'><\/p>\n\t\t\t\t\t\t\t<p class='gform_required_legend'>&quot;<span class=\"gfield_required gfield_required_asterisk\">*<\/span>&quot; indica i campi obbligatori<\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_1'  action='\/wikimuseums\/wp-json\/wp\/v2\/pages\/1557' data-formid='1' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_1' class='gform_fields top_label form_sublabel_above description_above validation_below'><fieldset id=\"field_1_1\" class=\"gfield gfield--type-name gfield--input-type-name gfield_contains_required field_sublabel_above gfield--no-description field_description_above field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_1_1\" ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Nome<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_1_1'>\n                            \n                            <span id='input_1_1_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <label for='input_1_1_3' class='gform-field-label gform-field-label--type-sub '>Nome<\/label>\n                                                    <input type='text' name='input_1.3' id='input_1_1_3' value=''   aria-required='true'    autocomplete=\"given-name\" \/>\n                                                <\/span>\n                            \n                            <span id='input_1_1_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                            <label for='input_1_1_6' class='gform-field-label gform-field-label--type-sub '>Cognome<\/label>\n                                                            <input type='text' name='input_1.6' id='input_1_1_6' value=''   aria-required='true'    autocomplete=\"family-name\" \/>\n                                                        <\/span>\n                            \n                        <\/div><\/fieldset><div id=\"field_1_4\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-half gfield_contains_required field_sublabel_above gfield--no-description field_description_above field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_1_4\" ><label class='gfield_label gform-field-label' for='input_1_4'>Telefono<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_4' id='input_1_4' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/> <\/div><\/div><div id=\"field_1_2\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-half gfield_contains_required field_sublabel_above gfield--no-description field_description_above field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_1_2\" ><label class='gfield_label gform-field-label' for='input_1_2'>Email<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_1_2' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_1_3\" class=\"gfield gfield--type-textarea gfield--input-type-textarea gfield_contains_required field_sublabel_above gfield--has-description field_description_above field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_1_3\" ><label class='gfield_label gform-field-label' for='input_1_3'>Richiesta<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='gfield_description' id='gfield_description_1_3'> Hai una domanda da farci? Chiedi pure.<\/div><div class='ginput_container ginput_container_textarea'><textarea name='input_3' id='input_1_3' class='textarea medium'  aria-describedby=\"gfield_description_1_3\" maxlength='600'  aria-required=\"true\" aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><fieldset id=\"field_1_5\" class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent gfield--width-full field_sublabel_above gfield--no-description field_description_above field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_1_5\" ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Consenso<\/legend><div class='ginput_container ginput_container_consent'><input name='input_5.1' id='input_1_5_1' type='checkbox' value='1'    aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_1_5_1' >Sottoscrivo la <a href=\"http:\/\/www.bamstrategieculturali.com\/wikimuseums\/wp-content\/uploads\/2024\/04\/Privacy-policy-wikimuseums.com_26.04.24.docx.pdf\">Privacy Policy<\/a>.<\/label><input type='hidden' name='input_5.2' value='Sottoscrivo la &lt;a href=&quot;http:\/\/www.bamstrategieculturali.com\/wikimuseums\/wp-content\/uploads\/2024\/04\/Privacy-policy-wikimuseums.com_26.04.24.docx.pdf&quot;&gt;Privacy Policy&lt;\/a&gt;.' class='gform_hidden' \/><input type='hidden' name='input_5.3' value='1' class='gform_hidden' \/><\/div><\/fieldset><\/div><\/div>\n        <div class='gform_footer top_label'> <input type='submit' id='gform_submit_button_1' class='gform_button button' value='Invia'  onclick='if(window[\"gf_submitting_1\"]){return false;}  if( !jQuery(\"#gform_1\")[0].checkValidity || jQuery(\"#gform_1\")[0].checkValidity()){window[\"gf_submitting_1\"]=true;}  ' onkeypress='if( event.keyCode == 13 ){ if(window[\"gf_submitting_1\"]){return false;} if( !jQuery(\"#gform_1\")[0].checkValidity || jQuery(\"#gform_1\")[0].checkValidity()){window[\"gf_submitting_1\"]=true;}  jQuery(\"#gform_1\").trigger(\"submit\",[true]); }' \/> \n            <input type='hidden' class='gform_hidden' name='is_submit_1' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='1' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_1' value='WyJ7XCI1LjFcIjpcIjQyNGI4ZDQ3ODdmZDFlNjYyOGE3NzRiNWVhN2IwOTFkXCIsXCI1LjJcIjpcIjIyMTk4MGMwYWI0MmNmMjE0ZjU1MTRjN2ViZDk4NmU1XCIsXCI1LjNcIjpcIjQyNGI4ZDQ3ODdmZDFlNjYyOGE3NzRiNWVhN2IwOTFkXCJ9IiwiZWQxYTM1MjQ3NDQyNjljNzBkZjQxOWViOTk2ZTRhYjYiXQ==' \/>\n            <input type='hidden' class='gform_hidden' name='gform_target_page_number_1' id='gform_target_page_number_1' value='0' \/>\n            <input type='hidden' class='gform_hidden' name='gform_source_page_number_1' id='gform_source_page_number_1' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"240\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><\/form>\n                        <\/div><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 1, 'https:\/\/www.bamstrategieculturali.com\/wikimuseums\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', false );jQuery('#gform_ajax_frame_1').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_1');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_1').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_1').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_1').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_1').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_1').val();gformInitSpinner( 1, 'https:\/\/www.bamstrategieculturali.com\/wikimuseums\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', false );jQuery(document).trigger('gform_page_loaded', [1, current_page]);window['gf_submitting_1'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_1').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [1]);window['gf_submitting_1'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_1').text());}else{jQuery('#gform_1').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"1\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);                if (event && event.defaultPrevented) {                return;         }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_1\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_1\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_1\" );        let postRenderFired = false;                function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            jQuery( document ).trigger( 'gform_post_render', [1, current_page] );            gform.utils.trigger( { event: 'gform\/postRender', native: false, data: { formId: 1, currentPage: current_page } } );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Hai visto le edizioni passate di Wikimuseums Napoli e Cesena e vorresti portarlo nel tuo museo, archivio o biblioteca? Questa \u00e8 la pagina in cui vediamo come farlo accadere insieme! [vc_column][vc_column_text css=&#8221;&#8221;]Wikimuseums \u00e8 un format pensato per rendere i beni culturali pi\u00f9 accessibili, attraverso il coinvolgimento diretto dei pubblici e delle community nella creazione di&nbsp;<\/p>\n<p><a class=\"btn btn-style\" href=\"https:\/\/www.bamstrategieculturali.com\/wikimuseums\/ospita-wikimuseums\/\">Continue Reading<\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/www.bamstrategieculturali.com\/wikimuseums\/wp-json\/wp\/v2\/pages\/1557"}],"collection":[{"href":"https:\/\/www.bamstrategieculturali.com\/wikimuseums\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bamstrategieculturali.com\/wikimuseums\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bamstrategieculturali.com\/wikimuseums\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bamstrategieculturali.com\/wikimuseums\/wp-json\/wp\/v2\/comments?post=1557"}],"version-history":[{"count":13,"href":"https:\/\/www.bamstrategieculturali.com\/wikimuseums\/wp-json\/wp\/v2\/pages\/1557\/revisions"}],"predecessor-version":[{"id":1650,"href":"https:\/\/www.bamstrategieculturali.com\/wikimuseums\/wp-json\/wp\/v2\/pages\/1557\/revisions\/1650"}],"wp:attachment":[{"href":"https:\/\/www.bamstrategieculturali.com\/wikimuseums\/wp-json\/wp\/v2\/media?parent=1557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}